{"id":18941,"date":"2024-08-28T11:08:18","date_gmt":"2024-08-28T11:08:18","guid":{"rendered":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/2024\/08\/111.jpeg"},"modified":"2024-08-28T11:08:18","modified_gmt":"2024-08-28T11:08:18","slug":"111","status":"inherit","type":"attachment","link":"https:\/\/med.aswu.edu.eg\/en\/111\/","title":{"rendered":"111"},"author":4,"comment_status":"","ping_status":"closed","template":"","meta":[],"media_folder":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111.jpeg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"191\" src=\"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-300x191.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-300x191.jpeg 300w, https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111.jpeg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":550,"height":350,"file":"slider266\/111.jpeg","filesize":181716,"sizes":{"medium":{"file":"111-300x191.jpeg","width":300,"height":191,"filesize":10682,"mime_type":"image\/jpeg","source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-300x191.jpeg"},"thumbnail":{"file":"111-150x150.jpeg","width":150,"height":150,"filesize":5461,"mime_type":"image\/jpeg","source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-150x150.jpeg"},"alante-thinkup-column2-1\/2":{"file":"111-550x285.jpeg","width":550,"height":285,"filesize":23106,"mime_type":"image\/jpeg","source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-550x285.jpeg"},"alante-thinkup-column3-2\/3":{"file":"111-380x254.jpeg","width":380,"height":254,"filesize":15184,"mime_type":"image\/jpeg","source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111-380x254.jpeg"},"full":{"file":"111.jpeg","width":550,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/med.aswu.edu.eg\/en\/wp-content\/uploads\/slider266\/111.jpeg","_links":{"self":[{"href":"https:\/\/med.aswu.edu.eg\/en\/wp-json\/wp\/v2\/media\/18941"}],"collection":[{"href":"https:\/\/med.aswu.edu.eg\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/med.aswu.edu.eg\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/med.aswu.edu.eg\/en\/wp-json\/wp\/v2\/users\/4"}],"wp:term":[{"taxonomy":"media_folder","embeddable":true,"href":"https:\/\/med.aswu.edu.eg\/en\/wp-json\/wp\/v2\/media_folder?post=18941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}